{"id":7068,"date":"2016-10-13T18:29:56","date_gmt":"2016-10-13T16:29:56","guid":{"rendered":"http:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/"},"modified":"2016-10-13T18:30:43","modified_gmt":"2016-10-13T16:30:43","slug":"coaching-las-empresas-tambien-necesitan-entrenar","status":"publish","type":"post","link":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/","title":{"rendered":"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR"},"content":{"rendered":"<p>Se trata de un procedimiento que ayuda e instruye a una persona o un colectivo con la finalidad de cumplir metas o desarrollar habilidades espec\u00edficas<\/p>\n<ul>\n<li>Con esta t\u00e9cnica las empresas buscan mejorar el rendimiento, facilitar el aprendizaje y el desarrollo de su equipo<\/li>\n<li>Seg\u00fan un estudio, un 88% de las empresas encuestadas asegura que este m\u00e9todo de entrenamiento proporciona retorno de la inversi\u00f3n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>En los \u00faltimos a\u00f1os, el t\u00e9rmino anglosaj\u00f3n \u2018coach\u2019, entrenador o preparador en castellano, se ha instalado en la sociedad procedente del \u00e1mbito deportivo. El coaching o m\u00e9todo de entrenamiento es ya una realidad. Se trata de una disciplina que ayuda e instruye a una persona o un colectivo con la finalidad de cumplir metas o desarrollar habilidades espec\u00edficas utilizando los propios recursos. Su acogida ha sido tal que muchas empresas lo demandan como parte fundamental del negocio para mejorar el rendimiento y lograr sus objetivos.<\/p>\n<p>Existen diversos m\u00e9todos y aplicaciones dependiendo de a qui\u00e9n va dirigido y la t\u00e9cnica que se utiliza. El coaching puede centrarse, por ejemplo, en mejorar las competencias de un individuo, orientarse a la formaci\u00f3n de l\u00edderes y equipos, colaborar en el hallazgo de \u00e1reas de oportunidad en grandes organizaciones o en la mejora estructural de las empresas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>EN QU\u00c9 CONSISTE<\/strong><\/p>\n<p><strong>&#8220;El coaching sirve para fomentar el rendimiento, facilitar el aprendizaje y el desarrollo en el entorno empresarial&#8221;<\/strong><\/p>\n<p>Arantxa Quintana, coach empresarial, describe en qu\u00e9 consiste su trabajo en las compa\u00f1\u00edas y a qui\u00e9nes va dirigido. \u201cA trav\u00e9s del coaching mejoramos o ayudamos a poner en visi\u00f3n a los miembros de la empresa, se puede trabajar con el consejo de direcci\u00f3n pasando por mandos intermedios hasta llegar a la \u00faltima persona de la organizaci\u00f3n\u201d. Este m\u00e9todo, seg\u00fan Quintana,\u00a0<strong>consiste en un acompa\u00f1amiento hacia un objetivo alcanzable, ayuda a descubrir \u00e1reas de mejora y fortalezas, a saber cu\u00e1les son los l\u00edmites<\/strong>\u00a0y a poner el foco en el futuro. \u201cLas empresas buscan objetivos y adem\u00e1s que sean cuantificables, todo ello depende de las personas que integran la organizaci\u00f3n, de los equipos, de los productos y clientes con los que trabajan, ah\u00ed est\u00e1 nuestro quehacer\u201d, describe la experta.<\/p>\n<p>Para Fernando Corral, profesor de direcci\u00f3n de recursos humanos y liderazgo en la Universidad Antonio de Nebrija y coach acreditado, el coaching es un procedimiento de desarrollo personalizado para una persona, grupo o equipo basado en una relaci\u00f3n de confianza y que sirve <strong>para fomentar el rendimiento, facilitar el aprendizaje y el desarrollo en el entorno empresarial.<\/strong><\/p>\n<p>En un proceso de coaching, el entrenador acompa\u00f1a a su cliente en el descubrimiento de aquellos puntos ciegos que puedan estar limitando sus resultados, anim\u00e1ndole a emprender nuevas acciones que le ayuden a desarrollar al m\u00e1ximo su potencial, explica Joan D\u00edaz, coach certificado, director de desarrollo de Negocio en Escuela Europea de Coaching (EEC). Este m\u00e9todo, por tanto, &#8220;optimiza las habilidades de los clientes, incrementa la eficacia de sus acciones, mejorando su bienestar profesional y personal&#8221;, asevera D\u00edaz.<\/p>\n<p>Este t\u00e9rmino no es nuevo. Se trata de un concepto que ya se utilizaba desde hace d\u00e9cadas en el \u00e1mbito deportivo y muchos de sus aspectos se han trasladado al entorno empresarial, cuyo desarrollo como tal ha despegado desde los a\u00f1os 80 y 90, indican los entendidos en la materia. Pero, \u00bfpor qu\u00e9 recurren las empresas a estos servicios?<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>DE LOS OBJETIVOS\u2026<\/strong><\/p>\n<p><strong>&#8220;Las empresas buscan con esta disciplina \u201cmejorar el rendimiento, facilitar el aprendizaje y el desarrollo&#8221;<\/strong><\/p>\n<p>\u201cLas empresas buscan con esta disciplina \u201cmejorar el rendimiento, facilitar el aprendizaje y el desarrollo. Hay ocasiones en que se utiliza con una intenci\u00f3n de impulsar todav\u00eda m\u00e1s un rendimiento excelente y otras en el que tiene una intenci\u00f3n correctiva\u201d, se\u00f1ala Fernando Corral.<\/p>\n<p>Para Susana Alonso, directora de la Escuela Internacional de Coaching Dial\u00f3gico del IDDI de la Universidad Francisco de Vitoria esta modalidad se ha puesto de moda porque &#8220;si se hace bien es muy efectivo&#8221;, subraya. Y argumenta en la misma l\u00ednea que Corral: &#8220;Se trata de hacer un acompa\u00f1amiento para conseguir mejor un objetivo personal y profesional, es decir, para <strong>conseguir una mejora del rendimiento de las personas, con una orientaci\u00f3n muy pr\u00e1ctica<\/strong>. Y eso est\u00e1 muy valorado por la empresas&#8221;, explica.<\/p>\n<p>En general, son tres los motivos por los que las empresas deciden acudir al coaching, detalla Joan D\u00edaz, tambi\u00e9n director de la EEC en Catalu\u00f1a. Uno el de<strong>\u00a0fomentar un estilo de liderazgo m\u00e1s inspirador<\/strong>, que pueda sacar lo mejor del equipo y conseguir que este se comprometa con los nuevos desaf\u00edos. Otro,\u00a0<strong>potenciar las habilidades como gestores del cambio dentro de la organizaci\u00f3n<\/strong>\u00a0y generar una mirada m\u00e1s creativa en los equipos. Y un \u00faltimo, crucial dada la situaci\u00f3n actual, el de\u00a0<strong>trabajar con los comit\u00e9s de direcci\u00f3n, generando una visi\u00f3n posibilitadora y ambiciosa<\/strong>, que les permita dibujar retos alcanzables. &#8220;Las empresas que revisan sus procesos y sus creencias limitantes salen reforzadas&#8221;, asegura D\u00edaz.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u2026 A LOS RESULTADOS<\/strong><\/p>\n<p>As\u00ed es. Las empresas, al contratar estos servicios, buscan resultados y parece que los consiguen. Seg\u00fan un estudio sobre coaching ejecutivo elaborado por la consultora brit\u00e1nica de capital humano HDA, un 97% de las organizaciones encuestadas creen que esta disciplina impacta positivamente en el rendimiento empresarial. Precisamente, la mejora en la productividad fue calificada como el beneficio principal de la aplicaci\u00f3n del coaching.\u00a0<strong>Un 88% de las empresas encuestadas aseguran que este \u2018m\u00e9todo de entrenamiento\u2019 proporciona retorno de la inversi\u00f3n (ROI).<\/strong><\/p>\n<p>Sin embargo el precio a pagar a cambio tambi\u00e9n es relevante. De acuerdo al informe\u00a0<em>La realidad del coaching en Espa\u00f1a 2016<\/em>\u00a0elaborado por Creantum, existe gran disparidad de precios en las sesiones de Coaching empresarial, si bien\u00a0<strong>una mayor\u00eda, el 26,9%, de los coaches encuestados reconoce que cobra entre 120 y 200 euros por sesi\u00f3n<\/strong>. Esta labor, tal y como explica Susana Alonso, de la Universidad Francisco de Vitoria debe ser ejercida \u201cpor un coach formado y preparado que cuente con las certificaciones adecuadas\u201d.<\/p>\n<p><strong>Un 97% de las organizaciones encuestadas creen que esta disciplina impacta positivamente en el rendimiento empresarial<\/strong><\/p>\n<p>No obstante, pese a ser tan efectivo como demuestran los estudios,\u00a0<strong>esta disciplina tambi\u00e9n se encuentra con cr\u00edticas<\/strong>. \u201cSe ha usado el coaching haciendo mala praxis, al haber personas que dec\u00edan ser coach y en realidad no lo eran, es decir, por intrusismo\u201d, reprocha Susana Alonso. Por su parte, Fernando Corral, coach y profesor de la Universidad Antonio de Nebrija, admite que \u201chay quien duda de que a trav\u00e9s de unas conversaciones \u2013por muy profesionales que sean- la persona pueda hacer cambios significativos en sus h\u00e1bitos de conducta, especialmente en personas con m\u00e1s edad y experiencia.\u201d<\/p>\n<p>Pese a todo, los profesionales y expertos en la materia defienden su disciplina, sus m\u00e9todos y herramientas de trabajo y recalcan las claves del \u00e9xito. \u201cCuando se dan las circunstancias de profesionalidad y experiencia del coach, de disposici\u00f3n del coachee al cambio y de apoyo por parte de la empresa, el coaching es altamente efectivo por su ayuda para probar nuevas pautas de conducta que le han llevado a conseguir resultados extraordinarios\u201d, explica Corral. Susana Alonso concluye: \u201cNuestro trabajo contribuye al desarrollo del liderazgo de las personas, tanto personal como profesional. Adem\u00e1s, el coaching empresarial tambi\u00e9n mejora las relaciones dentro de las organizaciones, y, en consecuencia, mejora el clima laboral\u201d.<\/p>\n<p>Des de <strong>Palomo Consultors, SL<\/strong> os animamos a contratar este servicio para impulsar su negocio.<\/p>\n<p>Nos enfocamos en la orientaci\u00f3n de los L\u00edderes para promover su crecimiento individual y el desarrollo de las Competencias y Habilidades que promover\u00e1n el crecimiento del talento en las Organizaciones.<\/p>\n<p>En definitiva, los beneficios del coaching son m\u00faltiples y por este motivo, cada vez son m\u00e1s las empresas que contratan uno o varios procesos para el desarrollo de su organizaci\u00f3n. Si todav\u00eda no lo ha hecho o tiene dudas sobre esta metodolog\u00eda no dude en contactar con nosotros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de un procedimiento que ayuda e instruye a una persona o un colectivo con la finalidad de cumplir metas o desarrollar habilidades espec\u00edficas Con esta t\u00e9cnica las empresas buscan mejorar el rendimiento, facilitar el aprendizaje y el desarrollo de su equipo Seg\u00fan un estudio, un 88% de las empresas encuestadas asegura que este [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[55],"tags":[],"class_list":["post-7068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR - Palomo Consultors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR - Palomo Consultors\" \/>\n<meta property=\"og:description\" content=\"Se trata de un procedimiento que ayuda e instruye a una persona o un colectivo con la finalidad de cumplir metas o desarrollar habilidades espec\u00edficas Con esta t\u00e9cnica las empresas buscan mejorar el rendimiento, facilitar el aprendizaje y el desarrollo de su equipo Seg\u00fan un estudio, un 88% de las empresas encuestadas asegura que este [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/\" \/>\n<meta property=\"og:site_name\" content=\"Palomo Consultors\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-13T16:29:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-13T16:30:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/palomo.net\/wp-content\/uploads\/COACHING-EMPRESARIAL-IV.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Palomo Consultors\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Palomo Consultors\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/\"},\"author\":{\"name\":\"Palomo Consultors\",\"@id\":\"https:\\\/\\\/palomo.net\\\/#\\\/schema\\\/person\\\/711f80f8e4fbf3466bd3c1c42e621ece\"},\"headline\":\"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR\",\"datePublished\":\"2016-10-13T16:29:56+00:00\",\"dateModified\":\"2016-10-13T16:30:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/\"},\"wordCount\":1377,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/palomo.net\\\/wp-content\\\/uploads\\\/COACHING-EMPRESARIAL-IV.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/\",\"url\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/\",\"name\":\"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR - Palomo Consultors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/palomo.net\\\/wp-content\\\/uploads\\\/COACHING-EMPRESARIAL-IV.jpg\",\"datePublished\":\"2016-10-13T16:29:56+00:00\",\"dateModified\":\"2016-10-13T16:30:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/#\\\/schema\\\/person\\\/711f80f8e4fbf3466bd3c1c42e621ece\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/palomo.net\\\/wp-content\\\/uploads\\\/COACHING-EMPRESARIAL-IV.jpg\",\"contentUrl\":\"https:\\\/\\\/palomo.net\\\/wp-content\\\/uploads\\\/COACHING-EMPRESARIAL-IV.jpg\",\"width\":400,\"height\":240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/coaching-las-empresas-tambien-necesitan-entrenar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/palomo.net\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/palomo.net\\\/#website\",\"url\":\"https:\\\/\\\/palomo.net\\\/\",\"name\":\"Palomo Consultors\",\"description\":\"Assessors Laborales d&#039; Empresas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/palomo.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/palomo.net\\\/#\\\/schema\\\/person\\\/711f80f8e4fbf3466bd3c1c42e621ece\",\"name\":\"Palomo Consultors\",\"url\":\"https:\\\/\\\/palomo.net\\\/ca\\\/author\\\/pl0mo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR - Palomo Consultors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/","og_locale":"ca_ES","og_type":"article","og_title":"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR - Palomo Consultors","og_description":"Se trata de un procedimiento que ayuda e instruye a una persona o un colectivo con la finalidad de cumplir metas o desarrollar habilidades espec\u00edficas Con esta t\u00e9cnica las empresas buscan mejorar el rendimiento, facilitar el aprendizaje y el desarrollo de su equipo Seg\u00fan un estudio, un 88% de las empresas encuestadas asegura que este [&hellip;]","og_url":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/","og_site_name":"Palomo Consultors","article_published_time":"2016-10-13T16:29:56+00:00","article_modified_time":"2016-10-13T16:30:43+00:00","og_image":[{"width":400,"height":240,"url":"https:\/\/palomo.net\/wp-content\/uploads\/COACHING-EMPRESARIAL-IV.jpg","type":"image\/jpeg"}],"author":"Palomo Consultors","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Palomo Consultors","Temps estimat de lectura":"7 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/#article","isPartOf":{"@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/"},"author":{"name":"Palomo Consultors","@id":"https:\/\/palomo.net\/#\/schema\/person\/711f80f8e4fbf3466bd3c1c42e621ece"},"headline":"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR","datePublished":"2016-10-13T16:29:56+00:00","dateModified":"2016-10-13T16:30:43+00:00","mainEntityOfPage":{"@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/"},"wordCount":1377,"commentCount":0,"image":{"@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/#primaryimage"},"thumbnailUrl":"https:\/\/palomo.net\/wp-content\/uploads\/COACHING-EMPRESARIAL-IV.jpg","articleSection":["Blog"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/","url":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/","name":"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR - Palomo Consultors","isPartOf":{"@id":"https:\/\/palomo.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/#primaryimage"},"image":{"@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/#primaryimage"},"thumbnailUrl":"https:\/\/palomo.net\/wp-content\/uploads\/COACHING-EMPRESARIAL-IV.jpg","datePublished":"2016-10-13T16:29:56+00:00","dateModified":"2016-10-13T16:30:43+00:00","author":{"@id":"https:\/\/palomo.net\/#\/schema\/person\/711f80f8e4fbf3466bd3c1c42e621ece"},"breadcrumb":{"@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/#primaryimage","url":"https:\/\/palomo.net\/wp-content\/uploads\/COACHING-EMPRESARIAL-IV.jpg","contentUrl":"https:\/\/palomo.net\/wp-content\/uploads\/COACHING-EMPRESARIAL-IV.jpg","width":400,"height":240},{"@type":"BreadcrumbList","@id":"https:\/\/palomo.net\/ca\/coaching-las-empresas-tambien-necesitan-entrenar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/palomo.net\/ca\/"},{"@type":"ListItem","position":2,"name":"COACHING: LAS EMPRESAS TAMBI\u00c9N NECESITAN ENTRENAR"}]},{"@type":"WebSite","@id":"https:\/\/palomo.net\/#website","url":"https:\/\/palomo.net\/","name":"Palomo Consultors","description":"Assessors Laborales d&#039; Empresas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palomo.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/palomo.net\/#\/schema\/person\/711f80f8e4fbf3466bd3c1c42e621ece","name":"Palomo Consultors","url":"https:\/\/palomo.net\/ca\/author\/pl0mo\/"}]}},"_links":{"self":[{"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/posts\/7068\/"}],"collection":[{"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/users\/4\/"}],"replies":[{"embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/comments\/?post=7068"}],"version-history":[{"count":1,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/posts\/7068\/revisions\/"}],"predecessor-version":[{"id":7069,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/posts\/7068\/revisions\/7069\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/media\/7066\/"}],"wp:attachment":[{"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/media\/?parent=7068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/categories\/?post=7068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/tags\/?post=7068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}