{"id":9034,"date":"2018-07-03T11:24:34","date_gmt":"2018-07-03T09:24:34","guid":{"rendered":"http:\/\/palomo.net\/la-afiliacion-media-a-la-seguridad-social\/"},"modified":"2018-07-03T11:24:34","modified_gmt":"2018-07-03T09:24:34","slug":"la-afiliacion-media-a-la-seguridad-social","status":"publish","type":"post","link":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/","title":{"rendered":"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL"},"content":{"rendered":"<p><strong>La afiliaci\u00f3n media a la Seguridad Social<\/strong> super\u00f3 en junio la barrera de los 19 millones de ocupados tras ascender en 91.322 afiliados, el 0,48%. En relaci\u00f3n al a\u00f1o pasado, el Sistema ha ganado 573.884 ocupados, el 3,11%. En concreto, destaca el buen comportamiento del R\u00e9gimen General, que incorpora 538.381 trabajadores (3,56%). n t\u00e9rminos anuales la ocupaci\u00f3n avanza en todas las provincias y Comunidades y Ciudades Aut\u00f3nomas destacando porcentualmente los incrementos de la Comunidad Valenciana (4,12%), Canarias (4,09%), Comunidad de Madrid (3,98%), Navarra (3,88%), Baleares (3,36%) y Andaluc\u00eda (3,15%).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La afiliaci\u00f3n media a la Seguridad Social super\u00f3 en junio la barrera de los 19 millones de ocupados tras ascender en 91.322 afiliados, el 0,48%. En relaci\u00f3n al a\u00f1o pasado, el Sistema ha ganado 573.884 ocupados, el 3,11%. En concreto, destaca el buen comportamiento del R\u00e9gimen General, que incorpora 538.381 trabajadores (3,56%). n t\u00e9rminos anuales [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-9034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL - Palomo Consultors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL - Palomo Consultors\" \/>\n<meta property=\"og:description\" content=\"La afiliaci\u00f3n media a la Seguridad Social super\u00f3 en junio la barrera de los 19 millones de ocupados tras ascender en 91.322 afiliados, el 0,48%. En relaci\u00f3n al a\u00f1o pasado, el Sistema ha ganado 573.884 ocupados, el 3,11%. En concreto, destaca el buen comportamiento del R\u00e9gimen General, que incorpora 538.381 trabajadores (3,56%). n t\u00e9rminos anuales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/\" \/>\n<meta property=\"og:site_name\" content=\"Palomo Consultors\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-03T09:24:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/palomo.net\/wp-content\/uploads\/afiliaci\u00f3n-seguridad-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Palomo Consultors\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Palomo Consultors\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/\"},\"author\":{\"name\":\"Palomo Consultors\",\"@id\":\"https:\\\/\\\/palomo.net\\\/#\\\/schema\\\/person\\\/711f80f8e4fbf3466bd3c1c42e621ece\"},\"headline\":\"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL\",\"datePublished\":\"2018-07-03T09:24:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/\"},\"wordCount\":92,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/palomo.net\\\/wp-content\\\/uploads\\\/afiliaci\u00f3n-seguridad-social.jpg\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/\",\"url\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/\",\"name\":\"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL - Palomo Consultors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/palomo.net\\\/wp-content\\\/uploads\\\/afiliaci\u00f3n-seguridad-social.jpg\",\"datePublished\":\"2018-07-03T09:24:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/#\\\/schema\\\/person\\\/711f80f8e4fbf3466bd3c1c42e621ece\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/palomo.net\\\/wp-content\\\/uploads\\\/afiliaci\u00f3n-seguridad-social.jpg\",\"contentUrl\":\"https:\\\/\\\/palomo.net\\\/wp-content\\\/uploads\\\/afiliaci\u00f3n-seguridad-social.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/palomo.net\\\/ca\\\/la-afiliacion-media-a-la-seguridad-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/palomo.net\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/palomo.net\\\/#website\",\"url\":\"https:\\\/\\\/palomo.net\\\/\",\"name\":\"Palomo Consultors\",\"description\":\"Assessors Laborales d&#039; Empresas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/palomo.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/palomo.net\\\/#\\\/schema\\\/person\\\/711f80f8e4fbf3466bd3c1c42e621ece\",\"name\":\"Palomo Consultors\",\"url\":\"https:\\\/\\\/palomo.net\\\/ca\\\/author\\\/pl0mo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL - Palomo Consultors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/","og_locale":"ca_ES","og_type":"article","og_title":"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL - Palomo Consultors","og_description":"La afiliaci\u00f3n media a la Seguridad Social super\u00f3 en junio la barrera de los 19 millones de ocupados tras ascender en 91.322 afiliados, el 0,48%. En relaci\u00f3n al a\u00f1o pasado, el Sistema ha ganado 573.884 ocupados, el 3,11%. En concreto, destaca el buen comportamiento del R\u00e9gimen General, que incorpora 538.381 trabajadores (3,56%). n t\u00e9rminos anuales [&hellip;]","og_url":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/","og_site_name":"Palomo Consultors","article_published_time":"2018-07-03T09:24:34+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/palomo.net\/wp-content\/uploads\/afiliaci\u00f3n-seguridad-social.jpg","type":"image\/jpeg"}],"author":"Palomo Consultors","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Palomo Consultors"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/#article","isPartOf":{"@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/"},"author":{"name":"Palomo Consultors","@id":"https:\/\/palomo.net\/#\/schema\/person\/711f80f8e4fbf3466bd3c1c42e621ece"},"headline":"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL","datePublished":"2018-07-03T09:24:34+00:00","mainEntityOfPage":{"@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/"},"wordCount":92,"commentCount":0,"image":{"@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/#primaryimage"},"thumbnailUrl":"https:\/\/palomo.net\/wp-content\/uploads\/afiliaci\u00f3n-seguridad-social.jpg","articleSection":["Not\u00edcies"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/","url":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/","name":"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL - Palomo Consultors","isPartOf":{"@id":"https:\/\/palomo.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/#primaryimage"},"image":{"@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/#primaryimage"},"thumbnailUrl":"https:\/\/palomo.net\/wp-content\/uploads\/afiliaci\u00f3n-seguridad-social.jpg","datePublished":"2018-07-03T09:24:34+00:00","author":{"@id":"https:\/\/palomo.net\/#\/schema\/person\/711f80f8e4fbf3466bd3c1c42e621ece"},"breadcrumb":{"@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/#primaryimage","url":"https:\/\/palomo.net\/wp-content\/uploads\/afiliaci\u00f3n-seguridad-social.jpg","contentUrl":"https:\/\/palomo.net\/wp-content\/uploads\/afiliaci\u00f3n-seguridad-social.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/palomo.net\/ca\/la-afiliacion-media-a-la-seguridad-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/palomo.net\/ca\/"},{"@type":"ListItem","position":2,"name":"LA AFILIACI\u00d3N MEDIA A LA SEGURIDAD SOCIAL"}]},{"@type":"WebSite","@id":"https:\/\/palomo.net\/#website","url":"https:\/\/palomo.net\/","name":"Palomo Consultors","description":"Assessors Laborales d&#039; Empresas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/palomo.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/palomo.net\/#\/schema\/person\/711f80f8e4fbf3466bd3c1c42e621ece","name":"Palomo Consultors","url":"https:\/\/palomo.net\/ca\/author\/pl0mo\/"}]}},"_links":{"self":[{"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/posts\/9034\/"}],"collection":[{"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/users\/4\/"}],"replies":[{"embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/comments\/?post=9034"}],"version-history":[{"count":0,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/posts\/9034\/revisions\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/media\/9035\/"}],"wp:attachment":[{"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/media\/?parent=9034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/categories\/?post=9034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/palomo.net\/ca\/wp-json\/wp\/v2\/tags\/?post=9034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}